{"id":54604,"date":"2018-08-18T09:41:43","date_gmt":"2018-08-18T07:41:43","guid":{"rendered":"https:\/\/www.babyartikel.de\/magazin\/?p=54604"},"modified":"2025-02-25T13:54:37","modified_gmt":"2025-02-25T12:54:37","slug":"kleinkinder-fernsehen","status":"publish","type":"post","link":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen","title":{"rendered":"Kinder geh\u00f6ren nicht vor den Fernseher: Wahr oder falsch?"},"content":{"rendered":"<p>&bdquo;Mein Kind setze ich die ersten Jahre nicht vor den Fernseher.&ldquo; Bloggerin Mareike hatte schon vor der Geburt ihres Sohnes einen strikten Plan, was dieses Thema angeht. Sie hat auch jetzt noch eine klare Meinung dazu und m&ouml;chte ihr Kind bis zum Grundschulalter m&ouml;glichst von TV und Co. fernhalten. Aber kann man das als Eltern so durchziehen? Und schadet es den Kindern wirklich, wenn sie ab und zu fernsehen?<h2 class=\"wp-block-heading\" id=\"h-kleinkinder-und-fernsehen-studien-belegen-schlechten-einfluss\">Kleinkinder und Fernsehen: Studien belegen schlechten Einfluss<\/h2><p><strong>Kinder und Medien: F&uuml;r viele Eltern geh&ouml;rt das einfach nicht zusammen<\/strong>. Sei es&nbsp;<span style=\"float: none; background-color: transparent; color: #333333; cursor: text; font-family: 'Roboto',Helvetica,sans-serif; font-size: 16px; font-style: normal; font-variant: normal; font-weight: 400; letter-spacing: normal; text-align: left; text-decoration: none; text-indent: 0px;\">der Umgang mit dem Smartphone, <\/span>dem Laptop oder auch ganz klassisch dem Fernseher. Die festgebrannte Meinung: Das Licht schadet den Kinderaugen, die Bilder &uuml;berfordern das unausgereifte Gehirn. Sowieso sind klassische Spielzeuge und B&uuml;cher das Beste. Was ist dran an dieser Meinung? <strong>Es gibt verschiedene Studien, die sich mit dem Fernsehkonsum von Kindern und seinen Folgen besch&auml;ftigen.<\/strong><\/p><h3 class=\"wp-block-heading\" id=\"h-kinder-die-viel-fernsehen-sind-weniger-aktiv-und-essen-mehr-susses\">Kinder, die viel fernsehen, sind weniger aktiv und essen mehr S&uuml;&szlig;es<\/h3><p>Eine davon haben Wissenschaftler der Universit&auml;t von Montreal durchgef&uuml;hrt. Sie werteten daf&uuml;r Daten von 1314 Kindern aus, die im Rahmen der <a href=\"https:\/\/www.sciencedaily.com\/releases\/2010\/05\/100503161229.htm\">&bdquo;Quebec Longitudinal Study of Child Development Main Exposure&ldquo;<\/a> &uuml;ber mehrere Jahre hinweg befragt, untersucht und beobachtet worden waren. Zum Beispiel wurden die Eltern der teilnehmenden Kinder gefragt, wie viel ihre Kinder im Alter von 29 Monaten und 52 Monaten ferngesehen hatten. Lehrer und &Auml;rzte beurteilten im Rahmen der Studie <strong>die schulischen Leistungen sowie den psychosozialen und gesundheitlichen Status<\/strong> der Kinder im Alter von zehn Jahren. Diesen Ansatz w&auml;hlten sie, um m&ouml;gliche Sp&auml;tfolgen feststellen zu k&ouml;nnen.<\/p><div class=\"marketing-slot\"><div id=\"block-18\" class=\"content-post-widget marketing-slot-1 widget_block\"><a href=\"#\" class=\"newsletter_popup\" style=\"\n  display: inline-block;\n  box-shadow: 0 4px 10px rgba(0,0,0,0.1);\n  margin: 20px auto;\n  max-width: 800px;\n  width: 100%;\">\n  <img src=\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2025\/08\/NL-Banner-Magazin-8-25.webp\" alt=\"Newsletter Banner\" style=\"\n    width: 100%;\n    height: auto;\n    display: block;\" onclick=\"ga('send', 'event', 'banner', 'click', 'magazin-banner-newsletter-8-25');\">\n<\/a>\n\n\t<!-- Modal -->\n\t<div class=\"modal fade modal_popup\" id=\"newsletter_popup\" tabindex=\"-1\" aria-labelledby=\"exampleModalLabel\" aria-hidden=\"true\">\n\t\t<div class=\"modal-dialog modal-dialog-centered modal-dialog-scrollable\">\n\t\t\t<div class=\"modal-content\">\n\t\t\t\t<div class=\"modal-header small-header\">\n\t\t\t\t\t<h5 class=\"modal-title\" id=\"newsletterModalLabel\">\n\t\t\t\t\t\tNewsletter\t\t\t\t\t<\/h5>\n\t\t\t\t\t<button type=\"button\" class=\"btn-close small-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><\/button>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t<div class=\"newsletterForm-embed popup-form\">\n        <form name=\"newsletterSubscriptionForm\" id=\"newsletter_popup_6a9829639c29f_form\" data-newsletter-id=\"newsletter_popup_6a9829639c29f\" method=\"POST\">\n\n\t\t\t<input type=\"text\" name=\"website\" class=\"hidden\" tabindex=\"-1\" autocomplete=\"off\" style=\"position:absolute;left:-9999px;\">\n\t\t\t<input type=\"hidden\" name=\"ts\" value=\"1788356963\">\n\n\t\t\t                <input type=\"hidden\" name=\"emarsys-event-id\" value=\"3756\">\n            \n            \t\t\t<div class=\"mb-3\">\n\t\t\t\t<label for=\"date\" class=\"form-label\">Geburtstag\/ -termin Deines Babys<\/label>\n                <input type=\"date\" name=\"date\" class=\"input input--expand form-control\" required>\n\t\t\t<\/div>\n            \n\t\t\t<div class=\"mb-3\">\n\t\t\t\t<label for=\"email\" class=\"form-label\">E-Mail-Adresse<\/label>\n\t\t\t\t<input type=\"email\" name=\"email\" placeholder=\"E-Mail-Adresse\" class=\"input input--expand form-control\" required>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<button type=\"submit\" class=\"btn btn-primary\" data-track-campaign=\"newsletter_subscription\" data-track-page-type=\"post\" data-track-medium=\"banner\" data-track-position=\"center\" data-track-name=\"magazine_popup_newsletter\">Absenden<\/button>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"small mt-3\" style=\"font-weight:normal;\">\n\t\t\t\t\t\n\t\t\t<div class=\"mt-3\">\n\t\t\t\tJa, ich m&ouml;chte den Newsletter von Babyartikel.de erhalten und &uuml;ber Aktionen informiert werden.\n  Dabei darf mein Nutzungsverhalten (z. B. &Ouml;ffnungen und Klicks) zur Personalisierung ausgewertet werden.\n  Mehr finde ich in der <a href=\"\/de\/datenschutz\" style=\"text-decoration:underline\">Datenschutzerkl&auml;rung<\/a>.\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"small mb-3 mt-3\" style=\"font-weight:normal;\">\n\t\t\t\t\tJederzeit abbestellbar | <a href=\"\/de\/datenschutz\" style=\"text-decoration:underline\">\n\t\t\t\t\t\tDatenschutzerkl&auml;rung\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\n        <\/form>\n    <\/div>\n\t\n\t\t\t\t\t<div class=\"response-messages_newsletter_popup_6a9829639c29f\">\n\t\t\t\t\t\t<div class=\"alert alert-success success mt-3 mb-3 d-none\">\n\t\t\t\t\t\t\tNur noch ein Klick! Best&auml;tige Deine Anmeldung in der E-Mail, die du gleich erh&auml;ltst.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"error mt-3 mb-3 d-none\">\n\t\t\t\t\t\t\t<div class=\"alert alert-danger \">\n\t\t\t\t\t\t\t\tEin Fehler ist aufgetreten. Bitte versuche es sp&auml;ter erneut.\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"alert alert-danger other-2007 mt-3 mb-3 d-none\">\n\t\t\t\t\t\t\tUng&Atilde;&frac14;ltiges Datumsformat\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<\/div><!-- content-widget --><\/div><p>Das Ergebnis: Konkret zeigten diejenigen Kinder mit starkem Fernsehkonsum im Kleinkindalter eine um sieben Prozent reduziertere Mitarbeit im Unterricht. Au&szlig;erdem hatten sie eine um sechs Prozent niedrigere Listung in mathematischen F&auml;chern. <strong>Die physische Aktivit&auml;t nahm bei diesen Kindern sogar um zehn Prozent allgemein und um 13 Prozent an den Wochenenden ab<\/strong>. Der Konsum von S&uuml;&szlig;igkeiten lag ebenfalls um zehn Prozent h&ouml;her. Folglich war auch der Body Mass Index durchschnittlich um f&uuml;nf Prozent h&ouml;her als bei denjenigen Sch&uuml;lern, die als Kleinkinder wenig oder kein Fernsehen schauen durften. Die Studie stammt aus dem Jahre 2010.<\/p><h3 class=\"wp-block-heading\" id=\"h-kinder-die-viel-fernsehen-sind-schlechter-in-der-schule\">Kinder, die viel fernsehen, sind schlechter in der Schule<\/h3><p>Eine andere Studie aus Deutschland hat sich ebenfalls mit den Folgen des Fernsehkonsums von Kindern besch&auml;ftigt.&nbsp;Jungen und M&auml;dchen der vierten Klasse mit einem eigenen TV &bdquo;haben <strong>deutlich schlechtere Schulnoten in Deutsch, Mathematik und Sachkunde<\/strong>&bdquo;, lautet eines der Ergebnisse einer Analyse des Kriminologischen Forschungsinstitutes Niedersachsen. Die Untersuchung basiert auf einer repr&auml;sentativen Befragung von etwa 6000 Grundsch&uuml;lern aus sechs Bundesl&auml;ndern. Die Studie wurde 2006 vorgestellt.<\/p><div class=\"postslot1\">\t\t<div style=\"clear:both\"><\/div>\n\t\t\t\t\t\t<div id=\"productPanel789\" class=\"product-panel-bottom\">&nbsp;<\/div>\n\t\t\t\t\t\t<script type=\"module\">\n\t\t\t\t\t\t\trequestProductPanel(\"https:\/\/www.babyartikel.de\/magazin\/wp-content\/plugins\/wp-productpanel2\/ProductPanel.php\", \"?panel_type=automatic&basis_category=6-KS-BUE&basis_product=&swipe_mobile=1&postid=54604&template=auto&max=4&productPanelId=789&solrQuery=\", 789, 1);\n\t\t\t\t\t\t<\/script>\n\t\t\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/cdn.jsdelivr.net\/npm\/swiper@8\/swiper-bundle.min.css\"><\/div><div class=\"marketing-slot\"><div id=\"block-25\" class=\"content-post-widget marketing-slot-2 widget_block\"><a href=\"https:\/\/www.babyartikel.de\/de\/angebote\" data-track-link-click=\"true\" data-track-name=\"nyoutlet2026-magazin\" data-track-medium=\"banner-magazin-post\" data-track-campaign=\"magazin-banner-nyoutlet2026\" onclick=\"ga('send', 'event', 'banner', 'click', 'magazin-banner-nyoutlet2026');\" style=\"display:block;width:100%;text-align:center;\"><img src=\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2026\/01\/NY-Outlet-10-2026.webp\" alt=\"Sale\" style=\"max-width:100%;\"><\/a><\/div><!-- content-widget --><\/div><p class=\"atc-TextParagraph\">Verantwortlich f&uuml;r den zum Teil exzessiven Fernsehkonsum von Kindern sei unter anderem die &bdquo;viel zu fr&uuml;he&ldquo; Heranf&uuml;hrung an die neuen Medien. Das sagt&nbsp;der Leiter der Forschungseinrichtung, Christian Pfeiffer. Durch verschiedene Faktoren, so etwa die falsche Heranf&uuml;hrung an Medien, <strong>werde die Pers&ouml;nlichkeit der Kinder nicht mehr ausreichend gef&ouml;rdert<\/strong>. Pfeiffer widerspricht damit Annahmen, dass ein fr&uuml;her Umgang mit Fernseher, PC und anderen Medien hilfreich im Hinblick auf die sp&auml;teren technischen Anforderungen an Kinder sein kann. Eine erschreckende Zahl in der Studie: Fast jedes zweite Kind gab an, dass es ungefragt und so lange es m&ouml;chte fernsehen oder Videospiele spielen k&ouml;nne. Doch eigentlich brauchen Kinder bei der Auswahl geeigneter Fernsehsendungen und PC-Spiele &bdquo;die Aufmerksamkeit und Unterst&uuml;tzung von Erwachsenen&ldquo;, empfiehlt der Forscher.<\/p><h2 class=\"wp-block-heading\" id=\"h-kinder-und-fernsehen-meine-meinung\">Kinder und Fernsehen: Meine Meinung<\/h2><p>Ich finde, auch in Bezug auf die Studien:<strong> Es ist nicht von der Hand zu weisen, dass das Fernsehen und anderer starker Medienkonsum negative Folgen f&uuml;r Kinder hat. Vor allem f&uuml;r Kleinkinder.<\/strong> Denn&nbsp;der passive Fernsehkonsum verf&uuml;hrt die Kinder zu k&ouml;rperlicher Inaktivit&auml;t. Sie werden dazu erzogen, sich von Bildern und Unterhaltung &bdquo;berieseln&ldquo; zu lassen, anstatt selbst aktiv zu werden, zu spielen und zu lernen. K&ouml;rperliche und teils geistige Inaktivit&auml;t sind m&ouml;gliche und logische Folgen.<strong> Zudem gibt es meiner Meinung nach keine Programme oder Sendungen, die auf Kleinkinder abgestimmt w&auml;ren<\/strong>. Oder ihnen sinnvolle Inhalte vermitteln k&ouml;nnten. Es ist daher aus meiner Sicht sinnvoll, Kinder vom Fernseher und anderen Ger&auml;ten m&ouml;glichst fern zu halten.<\/p><p><strong>Daf&uuml;r spricht auch, dass zu viel Zeit vor dem Fernseher negative Folgen f&uuml;r die Sprachentwicklung von Kindern hat.<\/strong> Denn Kinder lernen vor allem &uuml;ber den Dialog, &uuml;ber Kommunikation, &uuml;ber Interaktion. Wenn sich Dein Kind nun vor den Fernseher setzt, bleibt all das nat&uuml;rlich aus. Viel besser ist es also, wenn Du Deinem Kind etwas vorliest und es darauf reagieren kann. Wenn Du es dabei anschaust, ihm Bilder zeigst und Dich aktiv mit ihm auseinandersetzt. Das best&auml;tigt laut welt.de auch eine Erkl&auml;rung der Amerikanische Akademie f&uuml;r P&auml;diatrie (AAP). Diese st&uuml;tzt sich auf etwa 50 Studien, die sich seit 1999 mit den Auswirkungen von Fernsehen und Videos auf Kinder unter zwei Jahren befassten. Unter anderem erkl&auml;rt eine Autorin der Akademie, dass fr&uuml;hzeitiger Kontakt mit Medien wie dem TV dazu f&uuml;hren kann, dass diese Kinder beim Schulstart sprachlich eher gehemmt seien.<\/p><h3 class=\"wp-block-heading\" id=\"h-kompromisse-finden\">Kompromisse finden<\/h3><p>Auf der anderen Seite wei&szlig; ich aber, dass wir als Eltern uns selbst auch nicht immer von den Medien fernhalten k&ouml;nnen. Wir machen es unseren Kindern mit der Nutzung von Smartphones, Laptop und Co. zum Teil vor. <strong>Daher finde ich Kompromisse nicht verwerflich und in gewissem Ma&szlig;e in Ordnung.<\/strong> Ein Kompromiss w&auml;re f&uuml;r mich, dass das Kind sich auch mal ein Bild auf dem Smartphone ansehen darf. Oder Oma und Opa im Videoanruf sieht. Kompromisse entstehen auch, wenn &auml;ltere Geschwisterkinder in der Familie sind. Diese m&ouml;chten und d&uuml;rfen vielleicht mal eine halbe Stunde fernsehen. Wenn dann ab und zu auf den Bildschirm geschaut wird, ist das kein Weltuntergang. <strong>Problematisch wird es aus meiner Sicht, wenn das Kleinkind ganz bewusst und &uuml;ber eine halbe Stunde vor dem Fernseher sitzt und aktiv das Geschehen verfolgt<\/strong>. Dann sollten Eltern darauf achten, das Kind durch Spielen abzulenken, bis das Geschwisterkind seine TV-Zeit genossen hat.<\/p><h3 class=\"wp-block-heading\" id=\"h-kinder-behutsam-an-medien-heranfuhren\">Kinder behutsam an Medien heranf&uuml;hren<\/h3><p>Allgemein finde ich einfach, dass wir unsere Kinder mit dem <strong>Umgang von Medien ganz langsam, sehr behutsam und nicht zu fr&uuml;h vertraut machen<\/strong> m&uuml;ssen. Sie geh&ouml;ren zum Leben und auch bei der Tagesmutter oder im Kindergarten werden sie fr&uuml;her oder sp&auml;ter mit Medien konfrontiert. Ganz davon fernhalten kann man sie ja doch nicht. Wir Eltern sollten uns einfach bewusst sein, welche Folgen sie f&uuml;r Kleinkinder haben k&ouml;nnen. <strong>Und wir sollten Medien nicht als Hilfsmittel nutzen, um Kids ruhig zu stellen<\/strong>. Denn dass lesen, lernen und spielen die besseren Alternativen sind, ist uns allen doch bewusst!<\/p><p>Auch das Deutsche Gr&uuml;ne Kreuz e.V. r&auml;t zu einem gem&auml;&szlig;igten Konsum von Medien. <strong>Eine vern&uuml;nftige Heranf&uuml;hrung sei ab dem Grundschulalter sinnvoll.<\/strong> Bis zu einer Stunde t&auml;glich fernzusehen sei dann akzeptabel. F&uuml;r Schulkinder sei es sinnvoll, dass Hausaufgaben auf keinen Fall vor dem Fernseher gemacht werden. Denn Bilder und Ton f&uuml;hren zu starker Ablenkung. Das Gehirn k&ouml;nne sich so Inhalte des Lernstoffes nicht lange merken. Plus: Eine Stunde vor dem Schlafengehen sollten Fernsehen oder Computer ebenfalls tabu sein. Ich finde: Das sind gute Richtwerte, an die sich Eltern und Kinder doch gut halten k&ouml;nnen! Wenn wir dann noch &uuml;berpr&uuml;fen, was sie sich ansehen, k&ouml;nnen wir daf&uuml;r sorgen, dass die Medien keinen negativen Einfluss auf unsere Spr&ouml;sslinge haben.<\/p><p><em><strong>Wie h&auml;ltst Du es mit dem Fernseher? D&uuml;rfen Deine Kinder fernsehen oder bleibt bei Euch die Glotze tags&uuml;ber aus? Wir freuen uns &uuml;ber Deinen Kommentar!<\/strong><\/em><\/p><div class=\"credits-overlay\" data-target=\".wp-image-54995\"><a href=\"#\" target=\"_blank\">@JenkoAtaman &ndash; Fotolia.com<\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&bdquo;Mein Kind setze ich die ersten Jahre nicht vor den Fernseher.&ldquo; Bloggerin Mareike hatte schon vor der Geburt ihres Sohnes einen strikten Plan, was dieses Thema angeht. Sie hat auch jetzt noch eine klare Meinung dazu und m&ouml;chte ihr Kind bis zum Grundschulalter m&ouml;glichst von TV und Co. fernhalten. Aber kann man das als Eltern [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen\">Weiterlesen&#8230;<\/a><\/p>\n","protected":false},"author":66,"featured_media":54995,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2825,1430,2802],"tags":[3339,481],"class_list":["post-54604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-erziehungstipps","category-kleinkind","category-mamablogger-berichten","tag-alltag-mit-kleinkind","tag-erziehung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kinder sollten nicht fernsehen: Wahr oder falsch? | Babyartikel.de Magazin<\/title>\n<meta name=\"description\" content=\"&quot;Mein Kind setze ich die ersten Jahre nicht vor den Fernseher.&quot; Mama-Bloggerin Mareike hat auch eine klare Meinung dazu. Aber kann man das als Eltern wirklich so durchziehen? Und schadet Kindern Fernsehen wirklich so sehr, wie oft behauptet wird?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kinder geh\u00f6ren nicht vor den Fernseher: Wahr oder falsch?\" \/>\n<meta property=\"og:description\" content=\"&quot;Mein Kind setze ich die ersten Jahre nicht vor den Fernseher.&quot; Mama-Bloggerin Mareike hat auch eine klare Meinung dazu. Aber kann man das als Eltern wirklich so durchziehen? Und schadet Kindern Fernsehen wirklich so sehr, wie oft behauptet wird?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen\" \/>\n<meta property=\"og:site_name\" content=\"Babyartikel.de Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-18T07:41:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T12:54:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.magazin.babyartikel.de\/magazin\/wp-content\/uploads\/2018\/08\/Kinder-fernsehen.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mareike Fangmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mareike Fangmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen\"},\"author\":{\"name\":\"Mareike Fangmann\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/ebca06311ba3b031c9bca7bf2502fd34\"},\"headline\":\"Kinder geh\u00f6ren nicht vor den Fernseher: Wahr oder falsch?\",\"datePublished\":\"2018-08-18T07:41:43+00:00\",\"dateModified\":\"2025-02-25T12:54:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen\"},\"wordCount\":1284,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#primaryimage\"},\"thumbnailUrl\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2018\/02\/Kleinkind_Fernsehen_Fotolia_144120386-e1519983756553.jpg\",\"keywords\":[\"alltag mit kleinkind\",\"erziehung\"],\"articleSection\":[\"Erziehungstipps\",\"Kleinkind\",\"Mamablogger berichten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen\",\"url\":\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen\",\"name\":\"Kinder sollten nicht fernsehen: Wahr oder falsch? | Babyartikel.de Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#primaryimage\"},\"thumbnailUrl\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2018\/02\/Kleinkind_Fernsehen_Fotolia_144120386-e1519983756553.jpg\",\"datePublished\":\"2018-08-18T07:41:43+00:00\",\"dateModified\":\"2025-02-25T12:54:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/ebca06311ba3b031c9bca7bf2502fd34\"},\"description\":\"\\\"Mein Kind setze ich die ersten Jahre nicht vor den Fernseher.\\\" Mama-Bloggerin Mareike hat auch eine klare Meinung dazu. Aber kann man das als Eltern wirklich so durchziehen? Und schadet Kindern Fernsehen wirklich so sehr, wie oft behauptet wird?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#primaryimage\",\"url\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2018\/02\/Kleinkind_Fernsehen_Fotolia_144120386-e1519983756553.jpg\",\"contentUrl\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2018\/02\/Kleinkind_Fernsehen_Fotolia_144120386-e1519983756553.jpg\",\"width\":1235,\"height\":986,\"caption\":\"Kleinkind Fernseher, fernsehen, Baby TV\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.babyartikel.de\/magazin\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kinder geh\u00f6ren nicht vor den Fernseher: Wahr oder falsch?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#website\",\"url\":\"https:\/\/www.babyartikel.de\/magazin\/\",\"name\":\"Babyartikel.de Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.babyartikel.de\/magazin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/ebca06311ba3b031c9bca7bf2502fd34\",\"name\":\"Mareike Fangmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2022\/05\/mareike-fangmann-mama-150x150.jpg\",\"url\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2022\/05\/mareike-fangmann-mama-150x150.jpg\",\"contentUrl\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2022\/05\/mareike-fangmann-mama-150x150.jpg\",\"caption\":\"Mareike Fangmann\"},\"description\":\"Schon mit 16 wusste ich, dass ich Journalistin werden m\u00f6chte. Damals wollte ich Promis ihre Geheimnisse entlocken und Geschichten schreiben, die ber\u00fchren oder Augen \u00f6ffnen. An Anekdoten aus meinem Alltag als Mama habe ich damals noch nicht gedacht, aber das Leben schreibt bekannterweise seine eigenen Geschichten \u2013 und meine passen sich ihm an. Ich schreibe zwar seit einigen Jahren tats\u00e4chlich \u00fcber Ber\u00fchrendes und (manchmal auch Un-)Bewegendes aus dem Alltag und der Welt, und das bei einem gro\u00dfen Medium in Hamburg. Aber als Elternteil wirst Du das kennen: Themen au\u00dferhalb des Baby-Kosmos sind besonders in der Anfangszeit unwichtiger denn je. Kein Promi der Welt ist dann noch so interessant wie das eigene Kind. Und ich bin froh, dass ich Dich in dieser Zeit mit Tipps zur Baby-Ausstattung, Hilfestellungen bei Problemen mit dem Stuhlgang, Stillen, Schlafen oder meinen Erfahrungen zum Leben mit Kleinkind unterst\u00fctzen kann.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/mareike-fangmann-476940ab\/\"],\"url\":\"https:\/\/www.babyartikel.de\/magazin\/author\/mareike\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kinder sollten nicht fernsehen: Wahr oder falsch? | Babyartikel.de Magazin","description":"\"Mein Kind setze ich die ersten Jahre nicht vor den Fernseher.\" Mama-Bloggerin Mareike hat auch eine klare Meinung dazu. Aber kann man das als Eltern wirklich so durchziehen? Und schadet Kindern Fernsehen wirklich so sehr, wie oft behauptet wird?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen","og_locale":"de_DE","og_type":"article","og_title":"Kinder geh\u00f6ren nicht vor den Fernseher: Wahr oder falsch?","og_description":"\"Mein Kind setze ich die ersten Jahre nicht vor den Fernseher.\" Mama-Bloggerin Mareike hat auch eine klare Meinung dazu. Aber kann man das als Eltern wirklich so durchziehen? Und schadet Kindern Fernsehen wirklich so sehr, wie oft behauptet wird?","og_url":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen","og_site_name":"Babyartikel.de Magazin","article_published_time":"2018-08-18T07:41:43+00:00","article_modified_time":"2025-02-25T12:54:37+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/cdn.magazin.babyartikel.de\/magazin\/wp-content\/uploads\/2018\/08\/Kinder-fernsehen.png","type":"image\/png"}],"author":"Mareike Fangmann","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Mareike Fangmann","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#article","isPartOf":{"@id":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen"},"author":{"name":"Mareike Fangmann","@id":"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/ebca06311ba3b031c9bca7bf2502fd34"},"headline":"Kinder geh\u00f6ren nicht vor den Fernseher: Wahr oder falsch?","datePublished":"2018-08-18T07:41:43+00:00","dateModified":"2025-02-25T12:54:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen"},"wordCount":1284,"commentCount":0,"image":{"@id":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#primaryimage"},"thumbnailUrl":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2018\/02\/Kleinkind_Fernsehen_Fotolia_144120386-e1519983756553.jpg","keywords":["alltag mit kleinkind","erziehung"],"articleSection":["Erziehungstipps","Kleinkind","Mamablogger berichten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen","url":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen","name":"Kinder sollten nicht fernsehen: Wahr oder falsch? | Babyartikel.de Magazin","isPartOf":{"@id":"https:\/\/www.babyartikel.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#primaryimage"},"image":{"@id":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#primaryimage"},"thumbnailUrl":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2018\/02\/Kleinkind_Fernsehen_Fotolia_144120386-e1519983756553.jpg","datePublished":"2018-08-18T07:41:43+00:00","dateModified":"2025-02-25T12:54:37+00:00","author":{"@id":"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/ebca06311ba3b031c9bca7bf2502fd34"},"description":"\"Mein Kind setze ich die ersten Jahre nicht vor den Fernseher.\" Mama-Bloggerin Mareike hat auch eine klare Meinung dazu. Aber kann man das als Eltern wirklich so durchziehen? Und schadet Kindern Fernsehen wirklich so sehr, wie oft behauptet wird?","breadcrumb":{"@id":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#primaryimage","url":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2018\/02\/Kleinkind_Fernsehen_Fotolia_144120386-e1519983756553.jpg","contentUrl":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2018\/02\/Kleinkind_Fernsehen_Fotolia_144120386-e1519983756553.jpg","width":1235,"height":986,"caption":"Kleinkind Fernseher, fernsehen, Baby TV"},{"@type":"BreadcrumbList","@id":"https:\/\/www.babyartikel.de\/magazin\/kleinkinder-fernsehen#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.babyartikel.de\/magazin"},{"@type":"ListItem","position":2,"name":"Kinder geh\u00f6ren nicht vor den Fernseher: Wahr oder falsch?"}]},{"@type":"WebSite","@id":"https:\/\/www.babyartikel.de\/magazin\/#website","url":"https:\/\/www.babyartikel.de\/magazin\/","name":"Babyartikel.de Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.babyartikel.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/ebca06311ba3b031c9bca7bf2502fd34","name":"Mareike Fangmann","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2022\/05\/mareike-fangmann-mama-150x150.jpg","url":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2022\/05\/mareike-fangmann-mama-150x150.jpg","contentUrl":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2022\/05\/mareike-fangmann-mama-150x150.jpg","caption":"Mareike Fangmann"},"description":"Schon mit 16 wusste ich, dass ich Journalistin werden m\u00f6chte. Damals wollte ich Promis ihre Geheimnisse entlocken und Geschichten schreiben, die ber\u00fchren oder Augen \u00f6ffnen. An Anekdoten aus meinem Alltag als Mama habe ich damals noch nicht gedacht, aber das Leben schreibt bekannterweise seine eigenen Geschichten \u2013 und meine passen sich ihm an. Ich schreibe zwar seit einigen Jahren tats\u00e4chlich \u00fcber Ber\u00fchrendes und (manchmal auch Un-)Bewegendes aus dem Alltag und der Welt, und das bei einem gro\u00dfen Medium in Hamburg. Aber als Elternteil wirst Du das kennen: Themen au\u00dferhalb des Baby-Kosmos sind besonders in der Anfangszeit unwichtiger denn je. Kein Promi der Welt ist dann noch so interessant wie das eigene Kind. Und ich bin froh, dass ich Dich in dieser Zeit mit Tipps zur Baby-Ausstattung, Hilfestellungen bei Problemen mit dem Stuhlgang, Stillen, Schlafen oder meinen Erfahrungen zum Leben mit Kleinkind unterst\u00fctzen kann.","sameAs":["https:\/\/www.linkedin.com\/in\/mareike-fangmann-476940ab\/"],"url":"https:\/\/www.babyartikel.de\/magazin\/author\/mareike"}]}},"abstract_sku":"","_links":{"self":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts\/54604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/comments?post=54604"}],"version-history":[{"count":21,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts\/54604\/revisions"}],"predecessor-version":[{"id":958392,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts\/54604\/revisions\/958392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/media\/54995"}],"wp:attachment":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/media?parent=54604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/categories?post=54604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/tags?post=54604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}