
{"id":8036,"date":"2015-04-20T08:00:41","date_gmt":"2015-04-20T06:00:41","guid":{"rendered":"\/magazin\/?p=8036"},"modified":"2017-06-27T11:09:15","modified_gmt":"2017-06-27T09:09:15","slug":"ich-moechte-mein-baby-tragen-worauf-muss-ich-achten","status":"publish","type":"post","link":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten","title":{"rendered":"Ich m\u00f6chte mein Baby tragen! Worauf muss ich achten?"},"content":{"rendered":"<p>Viele Babys wollen getragen werden. Damit man auch die H&auml;nde frei hat und der R&uuml;cken etwas entlastet wird, gibt es mittlerweile eine <a title=\"Das Baby tragen &ndash; In welcher Trage?\" href=\"\/magazin\/das-baby-tragen-in-welcher-trage\">Vielzahl von Tragehilfen<\/a>. Worauf Ihr beim <strong>Tragen<\/strong> Eures Babys achten solltet:<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-flat ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten\/#Welche_Vorteile_hat_das_Tragen\" >Welche Vorteile hat das Tragen?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten\/#Worauf_sollte_man_beim_Tragen_achten\" >Worauf sollte man beim Tragen achten?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten\/#Welche_Tragemoeglichkeiten_gibt_es\" >Welche Tragem&ouml;glichkeiten gibt es?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Welche_Vorteile_hat_das_Tragen\"><\/span>Welche Vorteile hat das Tragen?<span class=\"ez-toc-section-end\"><\/span><\/h2><ul>\n<li>getragene Babys sind zufriedener, weinen deutlich weniger<\/li>\n<li>durch die Bewegung werden die Sinne und der K&ouml;rper angeregt<\/li>\n<li>k&ouml;rperliche und geistige Entwicklung wird gef&ouml;rdert<\/li>\n<li>Bl&auml;hungen und Luft im Bauch werden besser gel&ouml;st<\/li>\n<li>durch die gleichbleibenden Bewegungen ist das Tragen unbedenklich und sanft<\/li>\n<li>Mutter hat die H&auml;nde frei f&uuml;r Hausarbeit, &auml;ltere Geschwister, Essen und Trinken<\/li>\n<li>man kommt &uuml;berall bequem hin (Bus, Bahn, Treppen, enge Wege &hellip;)<\/li>\n<\/ul><h2><span class=\"ez-toc-section\" id=\"Worauf_sollte_man_beim_Tragen_achten\"><\/span>Worauf sollte man beim Tragen achten?<span class=\"ez-toc-section-end\"><\/span><\/h2><ul>\n<li>bei kleinen Babys m&uuml;ssen R&uuml;cken und Kopf optimal gest&uuml;tzt sein<\/li>\n<li>der Steg, auf dem das Kind &bdquo;sitzt&ldquo;, reicht idealerweise von Kniekehle zu Kniekehle (Kind macht also keinen Spagat und die Beinchen h&auml;ngen nicht herunter)<\/li>\n<li>Kinder bitte nie mit Blickrichtung nach vorne Tragen, da so der R&uuml;cken sich nicht runden kann. Au&szlig;erdem bekommt das Baby zu viele Eindr&uuml;cke ab. Es dann keine M&ouml;glichkeit seinen Kopf wegzudrehen. Bei Jungs ist auch Hodendurchblutung durch die aufrechte Haltung behindert.<\/li>\n<li>die Tragehilfe sollte nicht nur gut f&uuml;rs Baby sein, sondern auch f&uuml;r den Tragenden<\/li>\n<li>die Tragehilfe sollte einfach in der Handhabung sein und<\/li>\n<li>sie sollte waschbar sein<\/li>\n<\/ul><h2><span class=\"ez-toc-section\" id=\"Welche_Tragemoeglichkeiten_gibt_es\"><\/span>Welche Tragem&ouml;glichkeiten gibt es?<span class=\"ez-toc-section-end\"><\/span><\/h2><ul>\n<li><strong>Tragetuch<\/strong>: Kann von der Geburt an bis zum Ende der Tragezeit genutzt werden. Es ist immer optimal an Baby und Tragenden anpassbar. Viele verschiedene Bindeweisen sind m&ouml;glich. Die Wickeltechnik bedarf allerdings etwas &Uuml;bung.<\/li>\n<li><strong>Komforttrage<\/strong>: Schnelles und bequemes Anlegen. Au&szlig;erdem kann man sie lange nutzen. Wenn das Kind von mehreren Leuten getragen wird, ist das Umstellen der Schnallen etwas umst&auml;ndlich. Gerade hier bitte auf die o.g. Merkmale achten.<\/li>\n<li><strong>Ringsling<\/strong>: Anlegen geht schnell und das Endergebnis &nbsp;sieht gut aus. Allerdings liegt die Belastung nur auf einer Schulter. Daher ist diese Variante nichts f&uuml;r l&auml;ngeres Tragen.<\/li>\n<li><strong>Mei Tai<\/strong>: Funktioniert &auml;hnlich wie eine Komforttrage, kann jedoch individueller&nbsp;angepasst werden und ist einfach in der Handhabung. Bitte beim Kauf auf Tragetuchstoff und eine Kopfst&uuml;tze achten.<\/li>\n<\/ul><p>Bevor Ihr Euch eine Tragehilfe zulegt, wendet euch bitte an Eure Hebamme oder eine Trageberaterin. Es gibt auch sehr viele nicht zu empfehlende Tragem&ouml;glichkeiten.<\/p><div class=\"credits-overlay\" data-target=\".wp-image-7789\"><a href=\"#\" target=\"_blank\">&copy; Dmitry Naumov &ndash; Fotolia<\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viele Babys wollen getragen werden. Damit man auch die H&auml;nde frei hat und der R&uuml;cken etwas entlastet wird, gibt es mittlerweile eine Vielzahl von Tragehilfen. Worauf Ihr beim Tragen Eures Babys achten solltet:Welche Vorteile hat das Tragen? getragene Babys sind zufriedener, weinen deutlich weniger durch die Bewegung werden die Sinne und der K&ouml;rper angeregt k&ouml;rperliche [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten\">Weiterlesen&#8230;<\/a><\/p>\n","protected":false},"author":26,"featured_media":7789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[79,2800,2818],"tags":[],"class_list":["post-8036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baby","category-hebammenarbeit","category-pflege-gesundheit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ich m\u00f6chte mein Baby tragen! Worauf muss ich achten? | Babyartikel.de Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ich m\u00f6chte mein Baby tragen! Worauf muss ich achten?\" \/>\n<meta property=\"og:description\" content=\"Viele Babys wollen getragen werden. Damit man auch die H&auml;nde frei hat und der R&uuml;cken etwas entlastet wird, gibt es mittlerweile eine Vielzahl von Tragehilfen. Worauf Ihr beim Tragen Eures Babys achten solltet:Welche Vorteile hat das Tragen? getragene Babys sind zufriedener, weinen deutlich weniger durch die Bewegung werden die Sinne und der K&ouml;rper angeregt k&ouml;rperliche [...]Weiterlesen...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten\" \/>\n<meta property=\"og:site_name\" content=\"Babyartikel.de Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-20T06:00:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-27T09:09:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/03\/Baby-im-Tragetuch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"1733\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hebamme Melanie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hebamme Melanie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten\"},\"author\":{\"name\":\"Hebamme Melanie\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/742db8d94ea816e8e7aded8440a050eb\"},\"headline\":\"Ich m\u00f6chte mein Baby tragen! Worauf muss ich achten?\",\"datePublished\":\"2015-04-20T06:00:41+00:00\",\"dateModified\":\"2017-06-27T09:09:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten\"},\"wordCount\":395,\"commentCount\":3,\"image\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#primaryimage\"},\"thumbnailUrl\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/03\/Baby-im-Tragetuch.jpg\",\"articleSection\":[\"Baby\",\"Hebammen-Beratung\",\"Pflege &amp; Gesundheit\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten\",\"url\":\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten\",\"name\":\"Ich m\u00f6chte mein Baby tragen! Worauf muss ich achten? | Babyartikel.de Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#primaryimage\"},\"thumbnailUrl\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/03\/Baby-im-Tragetuch.jpg\",\"datePublished\":\"2015-04-20T06:00:41+00:00\",\"dateModified\":\"2017-06-27T09:09:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/742db8d94ea816e8e7aded8440a050eb\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#primaryimage\",\"url\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/03\/Baby-im-Tragetuch.jpg\",\"contentUrl\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/03\/Baby-im-Tragetuch.jpg\",\"width\":1100,\"height\":1733,\"caption\":\"Baby im Tragetuch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.babyartikel.de\/magazin\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ich m\u00f6chte mein Baby tragen! Worauf muss ich achten?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#website\",\"url\":\"https:\/\/www.babyartikel.de\/magazin\/\",\"name\":\"Babyartikel.de Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.babyartikel.de\/magazin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/742db8d94ea816e8e7aded8440a050eb\",\"name\":\"Hebamme Melanie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2017\/01\/melanie-pani-150x150.jpg\",\"url\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2017\/01\/melanie-pani-150x150.jpg\",\"contentUrl\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2017\/01\/melanie-pani-150x150.jpg\",\"caption\":\"Hebamme Melanie\"},\"description\":\"Ich freue mich darauf Dich zu unterst\u00fctzen und zu beraten und Deinem \u201ekleinen Wunder\u201c den bestm\u00f6glichen Start ins Leben zu bereiten.\",\"url\":\"https:\/\/www.babyartikel.de\/magazin\/author\/melanie-pani\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ich m\u00f6chte mein Baby tragen! Worauf muss ich achten? | Babyartikel.de Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten","og_locale":"de_DE","og_type":"article","og_title":"Ich m\u00f6chte mein Baby tragen! Worauf muss ich achten?","og_description":"Viele Babys wollen getragen werden. Damit man auch die H&auml;nde frei hat und der R&uuml;cken etwas entlastet wird, gibt es mittlerweile eine Vielzahl von Tragehilfen. Worauf Ihr beim Tragen Eures Babys achten solltet:Welche Vorteile hat das Tragen? getragene Babys sind zufriedener, weinen deutlich weniger durch die Bewegung werden die Sinne und der K&ouml;rper angeregt k&ouml;rperliche [...]Weiterlesen...","og_url":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten","og_site_name":"Babyartikel.de Magazin","article_published_time":"2015-04-20T06:00:41+00:00","article_modified_time":"2017-06-27T09:09:15+00:00","og_image":[{"width":1100,"height":1733,"url":"https:\/\/www.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/03\/Baby-im-Tragetuch.jpg","type":"image\/jpeg"}],"author":"Hebamme Melanie","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hebamme Melanie","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#article","isPartOf":{"@id":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten"},"author":{"name":"Hebamme Melanie","@id":"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/742db8d94ea816e8e7aded8440a050eb"},"headline":"Ich m\u00f6chte mein Baby tragen! Worauf muss ich achten?","datePublished":"2015-04-20T06:00:41+00:00","dateModified":"2017-06-27T09:09:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten"},"wordCount":395,"commentCount":3,"image":{"@id":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#primaryimage"},"thumbnailUrl":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/03\/Baby-im-Tragetuch.jpg","articleSection":["Baby","Hebammen-Beratung","Pflege &amp; Gesundheit"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten","url":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten","name":"Ich m\u00f6chte mein Baby tragen! Worauf muss ich achten? | Babyartikel.de Magazin","isPartOf":{"@id":"https:\/\/www.babyartikel.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#primaryimage"},"image":{"@id":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#primaryimage"},"thumbnailUrl":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/03\/Baby-im-Tragetuch.jpg","datePublished":"2015-04-20T06:00:41+00:00","dateModified":"2017-06-27T09:09:15+00:00","author":{"@id":"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/742db8d94ea816e8e7aded8440a050eb"},"breadcrumb":{"@id":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#primaryimage","url":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/03\/Baby-im-Tragetuch.jpg","contentUrl":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/03\/Baby-im-Tragetuch.jpg","width":1100,"height":1733,"caption":"Baby im Tragetuch"},{"@type":"BreadcrumbList","@id":"https:\/\/www.babyartikel.de\/magazin\/ich-moechte-mein-baby-tragen-worauf-muss-ich-achten#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.babyartikel.de\/magazin"},{"@type":"ListItem","position":2,"name":"Ich m\u00f6chte mein Baby tragen! Worauf muss ich achten?"}]},{"@type":"WebSite","@id":"https:\/\/www.babyartikel.de\/magazin\/#website","url":"https:\/\/www.babyartikel.de\/magazin\/","name":"Babyartikel.de Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.babyartikel.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/742db8d94ea816e8e7aded8440a050eb","name":"Hebamme Melanie","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2017\/01\/melanie-pani-150x150.jpg","url":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2017\/01\/melanie-pani-150x150.jpg","contentUrl":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2017\/01\/melanie-pani-150x150.jpg","caption":"Hebamme Melanie"},"description":"Ich freue mich darauf Dich zu unterst\u00fctzen und zu beraten und Deinem \u201ekleinen Wunder\u201c den bestm\u00f6glichen Start ins Leben zu bereiten.","url":"https:\/\/www.babyartikel.de\/magazin\/author\/melanie-pani"}]}},"abstract_sku":"","_links":{"self":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts\/8036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/comments?post=8036"}],"version-history":[{"count":11,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts\/8036\/revisions"}],"predecessor-version":[{"id":49127,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts\/8036\/revisions\/49127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/media\/7789"}],"wp:attachment":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/media?parent=8036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/categories?post=8036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/tags?post=8036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}