{"id":9833,"date":"2015-06-19T08:11:15","date_gmt":"2015-06-19T06:11:15","guid":{"rendered":"\/magazin\/?p=9833"},"modified":"2020-10-20T09:33:00","modified_gmt":"2020-10-20T07:33:00","slug":"der-apgar-score","status":"publish","type":"post","link":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score","title":{"rendered":"Der Apgar-Score &#8211; Das sagt er aus"},"content":{"rendered":"<p>Direkt nach der Geburt wird der sogenannte Apgar-Score ermittelt. Das ist der erste Test und die U1-Untersuchung Deines Babys. Meistens wirst Du davon gar nicht viel mitbekommen. Aber dennoch ich Dir heute genau erkl&auml;ren, was der Apgar-Score ist, wie er ermittelt wird und was die Testergebnisse aussagen.<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-flat ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\/#Was_soll_der_Apgar-Score_zeigen\" >Was soll der Apgar-Score zeigen?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\/#Wie_funktioniert_der_Apgar_Test_genau\" >Wie funktioniert der Apgar Test genau?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\/#Was_bedeuten_die_Apgar-Score_Werte\" >Was bedeuten die Apgar-Score Werte?<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\/#Apgar-Score_Gesundheitsprobleme\" >Apgar-Score &amp;&nbsp;Gesundheitsprobleme?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Was_soll_der_Apgar-Score_zeigen\"><\/span>Was soll der Apgar-Score zeigen?<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Mit dem Apgar-Score soll der Zustand des Neugeborenen <a href=\"https:\/\/www.babyartikel.de\/magazin\/was-brauche-ich-als-mutter-in-den-ersten-tagen-nach-der-geburt\">nach einer Geburt<\/a> beurteilt werden. Es ist eine einfache, effektive und schmerzfreie Methode. Entwickelt wurde dieser Gesundheitstest von der amerikanischen Narkose&auml;rztin Dr. Virginia Apgar im Jahr 1953. Es werden <strong>f&uuml;nf Lebensfunktionen<\/strong>, jeweils <strong>nach einer, f&uuml;nf und zehn Lebensminuten ermittelt<\/strong>. Die Ergebnisse des Tests zeigen, wie das Baby die Geburt &uuml;berstanden hat, wie gut es den Anpassungsprozess au&szlig;erhalb des Mutterleibs bew&auml;ltigt und ob es sich nach anf&auml;nglichen Schwierigkeiten schnell erholt.<\/p><h2><span class=\"ez-toc-section\" id=\"Wie_funktioniert_der_Apgar_Test_genau\"><\/span>Wie funktioniert der Apgar Test genau?<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Wie oben schon erw&auml;hnt, werden f&uuml;nf Lebensfunktionen in der ersten, der f&uuml;nften und dann wieder in der zehnten Minute nach der Geburt Deines Kindes bewertet. Jeder Faktor bekommt eine Punktzahl zwischen Null und Zwei. Dann werden die Punktzahlen addiert. So kann eine Maximalpunktzahl von 10 erreicht werden.<\/p><div class=\"marketing-slot\"><div id=\"block-18\" class=\"content-post-widget marketing-slot-1 widget_block\"><a href=\"#\" class=\"newsletter_popup\" style=\"\n  display: inline-block;\n  box-shadow: 0 4px 10px rgba(0,0,0,0.1);\n  margin: 20px auto;\n  max-width: 800px;\n  width: 100%;\">\n  <img src=\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2025\/08\/NL-Banner-Magazin-8-25.webp\" alt=\"Newsletter Banner\" style=\"\n    width: 100%;\n    height: auto;\n    display: block;\" onclick=\"ga('send', 'event', 'banner', 'click', 'magazin-banner-newsletter-8-25');\">\n<\/a>\n\n\t<!-- Modal -->\n\t<div class=\"modal fade modal_popup\" id=\"newsletter_popup\" tabindex=\"-1\" aria-labelledby=\"exampleModalLabel\" aria-hidden=\"true\">\n\t\t<div class=\"modal-dialog modal-dialog-centered modal-dialog-scrollable\">\n\t\t\t<div class=\"modal-content\">\n\t\t\t\t<div class=\"modal-header small-header\">\n\t\t\t\t\t<h5 class=\"modal-title\" id=\"newsletterModalLabel\">\n\t\t\t\t\t\tNewsletter\t\t\t\t\t<\/h5>\n\t\t\t\t\t<button type=\"button\" class=\"btn-close small-close\" data-bs-dismiss=\"modal\" aria-label=\"Close\"><\/button>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"modal-body\">\n\t\t\t\t\t\t<div class=\"newsletterForm-embed popup-form\">\n        <form name=\"newsletterSubscriptionForm\" id=\"newsletter_popup_6a980ad97edd1_form\" data-newsletter-id=\"newsletter_popup_6a980ad97edd1\" method=\"POST\">\n\n\t\t\t<input type=\"text\" name=\"website\" class=\"hidden\" tabindex=\"-1\" autocomplete=\"off\" style=\"position:absolute;left:-9999px;\">\n\t\t\t<input type=\"hidden\" name=\"ts\" value=\"1788349145\">\n\n\t\t\t                <input type=\"hidden\" name=\"emarsys-event-id\" value=\"3756\">\n            \n            \t\t\t<div class=\"mb-3\">\n\t\t\t\t<label for=\"date\" class=\"form-label\">Geburtstag\/ -termin Deines Babys<\/label>\n                <input type=\"date\" name=\"date\" class=\"input input--expand form-control\" required>\n\t\t\t<\/div>\n            \n\t\t\t<div class=\"mb-3\">\n\t\t\t\t<label for=\"email\" class=\"form-label\">E-Mail-Adresse<\/label>\n\t\t\t\t<input type=\"email\" name=\"email\" placeholder=\"E-Mail-Adresse\" class=\"input input--expand form-control\" required>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<button type=\"submit\" class=\"btn btn-primary\" data-track-campaign=\"newsletter_subscription\" data-track-page-type=\"post\" data-track-medium=\"banner\" data-track-position=\"center\" data-track-name=\"magazine_popup_newsletter\">Absenden<\/button>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"small mt-3\" style=\"font-weight:normal;\">\n\t\t\t\t\t\n\t\t\t<div class=\"mt-3\">\n\t\t\t\tJa, ich m&ouml;chte den Newsletter von Babyartikel.de erhalten und &uuml;ber Aktionen informiert werden.\n  Dabei darf mein Nutzungsverhalten (z. B. &Ouml;ffnungen und Klicks) zur Personalisierung ausgewertet werden.\n  Mehr finde ich in der <a href=\"\/de\/datenschutz\" style=\"text-decoration:underline\">Datenschutzerkl&auml;rung<\/a>.\n\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"small mb-3 mt-3\" style=\"font-weight:normal;\">\n\t\t\t\t\tJederzeit abbestellbar | <a href=\"\/de\/datenschutz\" style=\"text-decoration:underline\">\n\t\t\t\t\t\tDatenschutzerkl&auml;rung\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\n        <\/form>\n    <\/div>\n\t\n\t\t\t\t\t<div class=\"response-messages_newsletter_popup_6a980ad97edd1\">\n\t\t\t\t\t\t<div class=\"alert alert-success success mt-3 mb-3 d-none\">\n\t\t\t\t\t\t\tNur noch ein Klick! Best&auml;tige Deine Anmeldung in der E-Mail, die du gleich erh&auml;ltst.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"error mt-3 mb-3 d-none\">\n\t\t\t\t\t\t\t<div class=\"alert alert-danger \">\n\t\t\t\t\t\t\t\tEin Fehler ist aufgetreten. Bitte versuche es sp&auml;ter erneut.\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"alert alert-danger other-2007 mt-3 mb-3 d-none\">\n\t\t\t\t\t\t\tUng&Atilde;&frac14;ltiges Datumsformat\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\t<\/div><!-- content-widget --><\/div><table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"121\">Akronym<\/td>\n<td valign=\"top\" width=\"121\">zu Beurteilen<\/td>\n<td valign=\"top\" width=\"121\">0 Punkte<\/td>\n<td valign=\"top\" width=\"121\">1 Punkt<\/td>\n<td valign=\"top\" width=\"121\">2 Punkte<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"121\"><b>A<\/b>ussehen<\/td>\n<td valign=\"top\" width=\"121\">Hautfarbe<\/td>\n<td valign=\"top\" width=\"121\">&uuml;berall blau<\/td>\n<td valign=\"top\" width=\"121\">K&ouml;rper rosig, H&auml;nde\/F&uuml;&szlig;e blau<\/td>\n<td valign=\"top\" width=\"121\">am ganzen K&ouml;rper rosig<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"121\"><b>P<\/b>uls<\/td>\n<td valign=\"top\" width=\"121\">Herzfrequenz<\/td>\n<td valign=\"top\" width=\"121\">kein Herzschlag<\/td>\n<td valign=\"top\" width=\"121\">weniger als 100 Schl&auml;ge\/Minute<\/td>\n<td valign=\"top\" width=\"121\">100 oder mehr Schl&auml;ge\/Minute<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"121\"><b>G<\/b>rundtonus<\/td>\n<td valign=\"top\" width=\"121\">Muskeltonus<\/td>\n<td valign=\"top\" width=\"121\">schlaff<\/td>\n<td valign=\"top\" width=\"121\">leichtes Beugen\/Strecken der Gliedma&szlig;en<\/td>\n<td valign=\"top\" width=\"121\">aktive Bewegungen<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"121\"><b>A<\/b>tmung<\/td>\n<td valign=\"top\" width=\"121\">Atmung<\/td>\n<td valign=\"top\" width=\"121\">keine<\/td>\n<td valign=\"top\" width=\"121\">langsam, unregelm&auml;&szlig;ig<\/td>\n<td valign=\"top\" width=\"121\">regelm&auml;&szlig;ig<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"121\"><b>R<\/b>eflexe<\/td>\n<td valign=\"top\" width=\"121\">Reflexresonanz<\/td>\n<td valign=\"top\" width=\"121\">keine<\/td>\n<td valign=\"top\" width=\"121\">grimassieren<\/td>\n<td valign=\"top\" width=\"121\">schreien, husten<\/td>\n<\/tr>\n<\/tbody>\n<\/table><h2><span class=\"ez-toc-section\" id=\"Was_bedeuten_die_Apgar-Score_Werte\"><\/span>\nWas bedeuten die Apgar-Score Werte?<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Nat&uuml;rlich wollen alle Eltern gerne die Bestnote 10 h&ouml;ren. An dieser Stelle muss ich Dir sagen, dass kaum ein Kind nach einer Lebensminute v&ouml;llig rosig ist und somit eine 10 erreicht. Man kann sagen, dass Werte zwischen 7 und 10 einen guten bis exzellenten Zustand Deines Kindes beschreiben und somit Dein Kind eine ganz normale Behandlung ben&ouml;tigt. Bei Werten zwischen 5 und 7 gilt Dein Kind als gef&auml;hrdet und ben&ouml;tigt eine Hilfestellung durch die Hebamme oder den Kinderarzt. Dies kann unterschiedlich aussehen, vielleicht stimuliert die Hebamme die Haut Deines Kindes oder unterst&uuml;rzt es mit etwas Sauerstoff vor der Nase. Neugeborene mit einem Apgar-Score unter f&uuml;nf befinden sich in einer nicht guten Verfassung und ben&ouml;tigen Hilfe von einem Kinderarzt.<\/p><h2><span class=\"ez-toc-section\" id=\"Apgar-Score_Gesundheitsprobleme\"><\/span>Apgar-Score &amp;&nbsp;Gesundheitsprobleme?<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Ein niedriger Apgar-Score erlaubt keine Vorhersage &uuml;ber m&ouml;gliche zuk&uuml;nftige Gesundheitsprobleme! Der Test kann durch Medikamentengabe (zum Beispiel Schmerzmittel) beeinflusst sein. Auch Fr&uuml;hgeborene k&ouml;nnen mit dem Apgar-Score nur unzureichend beurteilt werden, da sie m&ouml;glicherweise nur deshalb einen niedrigen Apgar-Score erhalten, weil sie unreif sind. Das Sch&ouml;ne am Apgar-Score ist seine einfache Durchf&uuml;hrung. Er kontrolliert schnell und zuverl&auml;ssig den Gesundheitszustand des Babys in den ersten Minuten auf dieser Welt. Denke also bitte immer daran, dass Dein Baby trotz niedrigen Wert meistens gesund sein wird bzw. sein kann.<\/p><div class=\"credits-overlay\" data-target=\".wp-image-822272\"><a href=\"#\" target=\"_blank\">&copy; Carolina K Smith MD &ndash; stock.adobe.com<\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Direkt nach der Geburt wird der sogenannte Apgar-Score ermittelt. Das ist der erste Test und die U1-Untersuchung Deines Babys. Meistens wirst Du davon gar nicht viel mitbekommen. Aber dennoch ich Dir heute genau erkl&auml;ren, was der Apgar-Score ist, wie er ermittelt wird und was die Testergebnisse aussagen.Was soll der Apgar-Score zeigen?Mit dem Apgar-Score soll der [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\">Weiterlesen&#8230;<\/a><\/p>\n","protected":false},"author":22,"featured_media":822272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2800,2819],"tags":[],"class_list":["post-9833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hebammenarbeit","category-u-untersuchungen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Apgar-Score - Was sagt er aus und wie wird er interpretiert?<\/title>\n<meta name=\"description\" content=\"Mit dem Apgar-Score werden in der 1., der 5. und der 10. Lebensminute Deines Babys bestimmte Werte gemessen. Welche, kannst Du hier lesen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Apgar-Score - Das sagt er aus\" \/>\n<meta property=\"og:description\" content=\"Mit dem Apgar-Score werden in der 1., der 5. und der 10. Lebensminute Deines Babys bestimmte Werte gemessen. Welche, kannst Du hier lesen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\" \/>\n<meta property=\"og:site_name\" content=\"Babyartikel.de Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-19T06:11:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-20T07:33:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/06\/Neugborenes-Baby-Apgar-Score-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hebamme Monika\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hebamme Monika\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\"},\"author\":{\"name\":\"Hebamme Monika\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/36f0c72df9948a8998645d18b27d72fe\"},\"headline\":\"Der Apgar-Score &#8211; Das sagt er aus\",\"datePublished\":\"2015-06-19T06:11:15+00:00\",\"dateModified\":\"2020-10-20T07:33:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\"},\"wordCount\":483,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#primaryimage\"},\"thumbnailUrl\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/06\/Neugborenes-Baby-Apgar-Score-scaled.jpeg\",\"articleSection\":[\"Hebammen-Beratung\",\"U-Untersuchungen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\",\"url\":\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\",\"name\":\"Apgar-Score - Was sagt er aus und wie wird er interpretiert?\",\"isPartOf\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#primaryimage\"},\"thumbnailUrl\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/06\/Neugborenes-Baby-Apgar-Score-scaled.jpeg\",\"datePublished\":\"2015-06-19T06:11:15+00:00\",\"dateModified\":\"2020-10-20T07:33:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/36f0c72df9948a8998645d18b27d72fe\"},\"description\":\"Mit dem Apgar-Score werden in der 1., der 5. und der 10. Lebensminute Deines Babys bestimmte Werte gemessen. Welche, kannst Du hier lesen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#primaryimage\",\"url\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/06\/Neugborenes-Baby-Apgar-Score-scaled.jpeg\",\"contentUrl\":\"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/06\/Neugborenes-Baby-Apgar-Score-scaled.jpeg\",\"width\":2560,\"height\":1703,\"caption\":\"Neugeborenes Baby Nabelschnur Apgar Score\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.babyartikel.de\/magazin\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Apgar-Score &#8211; Das sagt er aus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#website\",\"url\":\"https:\/\/www.babyartikel.de\/magazin\/\",\"name\":\"Babyartikel.de Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.babyartikel.de\/magazin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/36f0c72df9948a8998645d18b27d72fe\",\"name\":\"Hebamme Monika\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/a17ad20223f2e4436fdf8a599a177aebbbdb3a25398f4e6a61be6a3f6f062b89?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a17ad20223f2e4436fdf8a599a177aebbbdb3a25398f4e6a61be6a3f6f062b89?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a17ad20223f2e4436fdf8a599a177aebbbdb3a25398f4e6a61be6a3f6f062b89?s=96&d=mm&r=g\",\"caption\":\"Hebamme Monika\"},\"description\":\"Ich bin seit 2005 Hebamme und mein Beruf macht mir noch immer so viel Spa\u00df wie am ersten Tag. In einer gro\u00dfen Geburtsklinik habe ich schon an die 1600 Geburten begleiten d\u00fcrfen. Parallel arbeite ich als freiberufliche Hebamme und betreue werdende und junge M\u00fctter in der Schwangerenvorsorge, Geburtsvorbereitung, R\u00fcckbildungsgymnastik und im Wochenbett. Mein gr\u00f6\u00dftes Abenteuer erlebe ich aber im Moment in meinen vier W\u00e4nden, mit meinen Mann und unseren zwei S\u00f6hnen. (geboren 2013 und 2016)\",\"url\":\"https:\/\/www.babyartikel.de\/magazin\/author\/monika-rasch\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apgar-Score - Was sagt er aus und wie wird er interpretiert?","description":"Mit dem Apgar-Score werden in der 1., der 5. und der 10. Lebensminute Deines Babys bestimmte Werte gemessen. Welche, kannst Du hier lesen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score","og_locale":"de_DE","og_type":"article","og_title":"Der Apgar-Score - Das sagt er aus","og_description":"Mit dem Apgar-Score werden in der 1., der 5. und der 10. Lebensminute Deines Babys bestimmte Werte gemessen. Welche, kannst Du hier lesen.","og_url":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score","og_site_name":"Babyartikel.de Magazin","article_published_time":"2015-06-19T06:11:15+00:00","article_modified_time":"2020-10-20T07:33:00+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/www.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/06\/Neugborenes-Baby-Apgar-Score-scaled.jpeg","type":"image\/jpeg"}],"author":"Hebamme Monika","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hebamme Monika","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#article","isPartOf":{"@id":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score"},"author":{"name":"Hebamme Monika","@id":"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/36f0c72df9948a8998645d18b27d72fe"},"headline":"Der Apgar-Score &#8211; Das sagt er aus","datePublished":"2015-06-19T06:11:15+00:00","dateModified":"2020-10-20T07:33:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score"},"wordCount":483,"commentCount":0,"image":{"@id":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#primaryimage"},"thumbnailUrl":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/06\/Neugborenes-Baby-Apgar-Score-scaled.jpeg","articleSection":["Hebammen-Beratung","U-Untersuchungen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score","url":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score","name":"Apgar-Score - Was sagt er aus und wie wird er interpretiert?","isPartOf":{"@id":"https:\/\/www.babyartikel.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#primaryimage"},"image":{"@id":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#primaryimage"},"thumbnailUrl":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/06\/Neugborenes-Baby-Apgar-Score-scaled.jpeg","datePublished":"2015-06-19T06:11:15+00:00","dateModified":"2020-10-20T07:33:00+00:00","author":{"@id":"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/36f0c72df9948a8998645d18b27d72fe"},"description":"Mit dem Apgar-Score werden in der 1., der 5. und der 10. Lebensminute Deines Babys bestimmte Werte gemessen. Welche, kannst Du hier lesen.","breadcrumb":{"@id":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.babyartikel.de\/magazin\/der-apgar-score"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#primaryimage","url":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/06\/Neugborenes-Baby-Apgar-Score-scaled.jpeg","contentUrl":"https:\/\/media.babyartikel.de\/magazin\/wp-content\/uploads\/2015\/06\/Neugborenes-Baby-Apgar-Score-scaled.jpeg","width":2560,"height":1703,"caption":"Neugeborenes Baby Nabelschnur Apgar Score"},{"@type":"BreadcrumbList","@id":"https:\/\/www.babyartikel.de\/magazin\/der-apgar-score#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.babyartikel.de\/magazin"},{"@type":"ListItem","position":2,"name":"Der Apgar-Score &#8211; Das sagt er aus"}]},{"@type":"WebSite","@id":"https:\/\/www.babyartikel.de\/magazin\/#website","url":"https:\/\/www.babyartikel.de\/magazin\/","name":"Babyartikel.de Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.babyartikel.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.babyartikel.de\/magazin\/#\/schema\/person\/36f0c72df9948a8998645d18b27d72fe","name":"Hebamme Monika","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a17ad20223f2e4436fdf8a599a177aebbbdb3a25398f4e6a61be6a3f6f062b89?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a17ad20223f2e4436fdf8a599a177aebbbdb3a25398f4e6a61be6a3f6f062b89?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a17ad20223f2e4436fdf8a599a177aebbbdb3a25398f4e6a61be6a3f6f062b89?s=96&d=mm&r=g","caption":"Hebamme Monika"},"description":"Ich bin seit 2005 Hebamme und mein Beruf macht mir noch immer so viel Spa\u00df wie am ersten Tag. In einer gro\u00dfen Geburtsklinik habe ich schon an die 1600 Geburten begleiten d\u00fcrfen. Parallel arbeite ich als freiberufliche Hebamme und betreue werdende und junge M\u00fctter in der Schwangerenvorsorge, Geburtsvorbereitung, R\u00fcckbildungsgymnastik und im Wochenbett. Mein gr\u00f6\u00dftes Abenteuer erlebe ich aber im Moment in meinen vier W\u00e4nden, mit meinen Mann und unseren zwei S\u00f6hnen. (geboren 2013 und 2016)","url":"https:\/\/www.babyartikel.de\/magazin\/author\/monika-rasch"}]}},"abstract_sku":"","_links":{"self":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts\/9833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/comments?post=9833"}],"version-history":[{"count":9,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts\/9833\/revisions"}],"predecessor-version":[{"id":822273,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/posts\/9833\/revisions\/822273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/media\/822272"}],"wp:attachment":[{"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/media?parent=9833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/categories?post=9833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.babyartikel.de\/magazin\/wp-json\/wp\/v2\/tags?post=9833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}